{"id":2201,"date":"2025-10-08T12:59:46","date_gmt":"2025-10-08T10:59:46","guid":{"rendered":"https:\/\/tryghedsappen.dk\/fonctionnalites\/"},"modified":"2026-03-17T14:26:27","modified_gmt":"2026-03-17T13:26:27","slug":"fonctionnalites","status":"publish","type":"page","link":"https:\/\/tryghedsappen.dk\/fr\/fonctionnalites\/","title":{"rendered":"Fonctionnalit\u00e9s"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2201\" class=\"elementor elementor-2201 elementor-709\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dff67e e-flex e-con-boxed e-con e-parent\" data-id=\"2dff67e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6486bc5 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6486bc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fonctionnalit\u00e9s \u2013 S\u00e9curit\u00e9\nau quotidien<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93f43bb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"93f43bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Tryghedsappen est une application mobile d\u00e9velopp\u00e9e au Danemark, con\u00e7ue pour apporter de la s\u00e9curit\u00e9 au quotidien \u2014 pour vous, vos proches et votre r\u00e9seau.<\/p><p>Dune simple pression, vous pouvez alerter vos contacts durgence, partager votre position et obtenir un contact ou de laide le plus rapidement possible, lorsque vous en avez besoin. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca38bb5 e-flex e-con-boxed e-con e-parent\" data-id=\"ca38bb5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a74d04c e-con-full e-flex e-con e-child\" data-id=\"a74d04c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-59ec3de e-con-full e-flex e-con e-child\" data-id=\"59ec3de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28a069a elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"28a069a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"52\" viewBox=\"0 0 52 52\" fill=\"none\"><circle cx=\"26\" cy=\"26\" r=\"26\" fill=\"#F0F0F0\"><\/circle><path d=\"M38.8575 15.0563L26.7599 11.5226C26.5907 11.4731 26.41 11.4731 26.2406 11.5226L14.1428 15.0563C13.7606 15.1679 13.4989 15.5104 13.4989 15.8989V28.8555C13.4989 30.5407 14.1996 32.2659 15.5815 33.9829C16.637 35.2943 18.0971 36.6112 19.9215 37.897C22.9862 40.0569 26.004 41.3819 26.131 41.4372C26.2484 41.4884 26.3743 41.5141 26.5002 41.5141C26.626 41.5141 26.7519 41.4885 26.8694 41.4372C26.9964 41.3819 30.0141 40.0569 33.0788 37.897C34.9031 36.6112 36.3633 35.2943 37.4188 33.9829C38.8007 32.2659 39.5014 30.5408 39.5014 28.8555V15.8989C39.5014 15.5104 39.2397 15.1679 38.8575 15.0563ZM37.6943 28.8555C37.6943 31.8379 34.6208 34.6345 32.0424 36.4554C29.7308 38.0878 27.3866 39.2461 26.5002 39.6622C25.6139 39.2461 23.2696 38.0878 20.958 36.4554C18.3796 34.6345 15.306 31.8379 15.306 28.8555V16.5534L26.5002 13.2837L37.6943 16.5534V28.8555Z\" fill=\"#AF52DE\"><\/path><path d=\"M39.0022 15.8988C39.0023 15.7248 38.8849 15.5711 38.7138 15.5212L26.6169 11.9883L26.616 11.9873C26.5406 11.9654 26.4598 11.9661 26.3841 11.9883L14.2862 15.5212C14.1151 15.5712 13.9978 15.7248 13.9978 15.8988V28.8559C13.9979 30.4039 14.6406 32.0262 15.9738 33.6829C16.9932 34.9494 18.4165 36.2362 20.2143 37.5032C23.2347 39.6319 26.213 40.9406 26.3344 40.9934C26.387 41.0164 26.4437 41.0285 26.5 41.0285C26.5564 41.0285 26.6132 41.0173 26.6656 40.9944C26.7824 40.9436 29.7637 39.6337 32.7867 37.5032C34.5842 36.2363 36.0069 34.9493 37.0262 33.6829C38.3594 32.0262 39.0021 30.404 39.0022 28.8559V15.8988ZM37.1957 16.9139L26.5 13.7908L15.8052 16.9139V28.8559C15.8054 30.1858 16.4936 31.5232 17.5513 32.7835C18.604 34.0378 19.9794 35.1642 21.251 36.0622C23.3591 37.5509 25.5003 38.6394 26.5 39.1188C27.4996 38.6395 29.6415 37.5511 31.7499 36.0622C33.0214 35.1642 34.3961 34.0377 35.4487 32.7835C36.5065 31.5231 37.1956 30.1859 37.1957 28.8559V16.9139ZM38.1935 28.8559C38.1933 30.5081 37.3447 32.0598 36.2214 33.3983C35.0928 34.743 33.6423 35.9257 32.3355 36.8486C29.99 38.505 27.6161 39.6778 26.7173 40.0998L26.5 40.2013L26.2837 40.0998C25.3851 39.6779 23.0111 38.5051 20.6654 36.8486C19.3586 35.9257 17.9073 34.743 16.7786 33.3983C15.6553 32.0598 14.8076 30.5081 14.8075 28.8559V16.1919L15.1631 16.0885L26.5 12.7766L37.8379 16.0885L38.1935 16.1919V28.8559ZM40 28.8559C39.9999 30.678 39.2417 32.5055 37.8115 34.2824C36.7199 35.6387 35.2222 36.9861 33.3713 38.2906C31.0422 39.9321 28.7421 41.0963 27.679 41.6016L27.0729 41.8805C26.8906 41.96 26.6951 42 26.5 42C26.3046 42 26.1092 41.9599 25.9271 41.8805C25.7847 41.8185 22.7324 40.4781 19.6287 38.2906C17.7778 36.9862 16.2801 35.6387 15.1885 34.2824C13.7584 32.5055 13.0001 30.6779 13 28.8559V15.8988C13 15.2958 13.4065 14.7638 13.9997 14.5905L26.0976 11.0576C26.3604 10.9809 26.6406 10.9807 26.9034 11.0576L39.0013 14.5905C39.5944 14.7638 40 15.2959 40 15.8988V28.8559Z\" fill=\"#AF52DE\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLe bouton de s\u00e9curit\u00e9\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUne pression, et vos proches sont imm\u00e9diatement alert\u00e9s avec votre localisation et votre demande daide.\n\nLe bouton sutilise en cas durgence, de situation anxiog\u00e8ne \u2014 ou simplement lorsque vous souhaitez que vos contacts sachent que vous avez besoin daide et o\u00f9 vous vous trouvez.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47e5c86 e-con-full e-flex e-con e-child\" data-id=\"47e5c86\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-851507b elementor-widget elementor-widget-image\" data-id=\"851507b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"618\" height=\"362\" src=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Tryghedsknappen.png\" class=\"attachment-full size-full wp-image-2202\" alt=\"\" srcset=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Tryghedsknappen.png 618w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Tryghedsknappen-300x176.png 300w\" sizes=\"(max-width: 618px) 100vw, 618px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5828784 e-con-full e-flex e-con e-child\" data-id=\"5828784\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ff0cdb3 e-con-full e-flex e-con e-child\" data-id=\"ff0cdb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-283974c elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"283974c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"52\" viewBox=\"0 0 52 52\" fill=\"none\"><circle cx=\"26\" cy=\"26\" r=\"26\" fill=\"#F0F0F0\"><\/circle><path d=\"M26.0002 24.6666C28.022 24.6666 29.6668 23.0217 29.6668 20.9999C29.6668 18.9781 28.022 17.3333 26.0002 17.3333C23.9784 17.3333 22.3335 18.9781 22.3335 20.9999C22.3335 23.0217 23.9784 24.6666 26.0002 24.6666ZM26.0002 19.7777C26.6741 19.7777 27.2224 20.326 27.2224 20.9999C27.2224 21.6739 26.6741 22.2221 26.0002 22.2221C25.3262 22.2221 24.7779 21.6739 24.7779 20.9999C24.7779 20.326 25.3262 19.7777 26.0002 19.7777Z\" fill=\"#007AFF\"><\/path><path d=\"M37 20.9999C37 14.9345 32.0654 9.99994 26 9.99994C19.9346 9.99994 15 14.9345 15 20.9999C15 23.3995 15.7591 25.6799 17.1954 27.5947L23.0656 35.421C23.7551 36.3401 24.8521 36.8888 26 36.8888C27.1479 36.8888 28.2449 36.3401 28.9345 35.4209L34.8046 27.5947C36.2409 25.6799 37 23.3995 37 20.9999ZM32.8491 26.1279L26.9791 33.954C26.7452 34.2657 26.3884 34.4444 26 34.4444C25.6116 34.4444 25.2547 34.2657 25.021 33.9541L19.1509 26.1279C18.0345 24.6396 17.4444 22.8663 17.4444 20.9999C17.4444 16.2824 21.2825 12.4444 26 12.4444C30.7175 12.4444 34.5556 16.2824 34.5556 20.9999C34.5556 22.8663 33.9655 24.6396 32.8491 26.1279Z\" fill=\"#007AFF\"><\/path><path d=\"M32.1109 40.0666C32.1109 39.3915 31.5637 38.8444 30.8887 38.8444H21.1109C20.4359 38.8444 19.8887 39.3915 19.8887 40.0666C19.8887 40.7416 20.4359 41.2888 21.1109 41.2888H30.8887C31.5637 41.2888 32.1109 40.7416 32.1109 40.0666Z\" fill=\"#007AFF\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLocalisation en direct\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPartagez votre position en temps r\u00e9el avec vos proches et les personnes en qui vous avez confiance. Parfait lorsque vous rentrez seul(e) \u00e0 pied, que vous allez courir, ou simplement pour faire un point afin que la famille sache o\u00f9 vous \u00eates. \n\nLe bouton de s\u00e9curit\u00e9 ne remplace pas un appel d\u2019urgence au 112, mais contacte votre r\u00e9seau et vos proches imm\u00e9diatement.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d817a0 e-con-full e-flex e-con e-child\" data-id=\"5d817a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0181035 elementor-widget elementor-widget-image\" data-id=\"0181035\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1281645435-scaled.jpg\" class=\"attachment-full size-full wp-image-2217\" alt=\"\" srcset=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1281645435-scaled.jpg 2560w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1281645435-300x200.jpg 300w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1281645435-1024x683.jpg 1024w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1281645435-768x512.jpg 768w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1281645435-1536x1024.jpg 1536w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1281645435-2048x1366.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51b2354 e-con-full e-flex e-con e-child\" data-id=\"51b2354\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-062253f e-con-full e-flex e-con e-child\" data-id=\"062253f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-039c670 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"039c670\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"52\" viewBox=\"0 0 52 52\" fill=\"none\"><circle cx=\"26\" cy=\"26\" r=\"26\" fill=\"#F0F0F0\"><\/circle><path d=\"M25.3544 24.2761C26.4233 24.2761 27.4682 23.9591 28.357 23.3652C29.2457 22.7714 29.9384 21.9273 30.3474 20.9397C30.7564 19.9522 30.8633 18.8655 30.6547 17.8172C30.4461 16.7688 29.9313 15.8059 29.1754 15.0501C28.4195 14.2944 27.4564 13.7798 26.4081 13.5714C25.3597 13.363 24.273 13.4701 23.2856 13.8793C22.2981 14.2885 21.4541 14.9814 20.8604 15.8702C20.2667 16.7591 19.95 17.8041 19.9502 18.873C19.9519 20.3056 20.5219 21.6791 21.535 22.692C22.5482 23.705 23.9218 24.2746 25.3544 24.2761ZM25.3544 15.6562C25.9906 15.6562 26.6125 15.8449 27.1415 16.1984C27.6705 16.5518 28.0828 17.0542 28.3263 17.642C28.5697 18.2298 28.6334 18.8765 28.5093 19.5005C28.3852 20.1245 28.0788 20.6977 27.629 21.1475C27.1791 21.5974 26.6059 21.9038 25.982 22.0279C25.358 22.152 24.7112 22.0883 24.1234 21.8448C23.5357 21.6014 23.0333 21.1891 22.6798 20.6601C22.3264 20.1311 22.1377 19.5092 22.1377 18.873C22.1389 18.0202 22.4781 17.2027 23.0811 16.5997C23.6841 15.9967 24.5016 15.6574 25.3544 15.6562Z\" fill=\"#0BAE79\"><\/path><path d=\"M15.1455 27.4523C15.9675 27.4523 16.7711 27.2086 17.4546 26.7519C18.1381 26.2952 18.6708 25.6461 18.9854 24.8866C19.3 24.1272 19.3823 23.2915 19.2219 22.4852C19.0615 21.679 18.6657 20.9384 18.0844 20.3572C17.5032 19.7759 16.7626 19.3801 15.9564 19.2197C15.1501 19.0593 14.3144 19.1416 13.555 19.4562C12.7955 19.7708 12.1464 20.3035 11.6897 20.987C11.233 21.6705 10.9893 22.4741 10.9893 23.2961C10.9893 24.3984 11.4271 25.4555 12.2066 26.235C12.986 27.0144 14.0432 27.4523 15.1455 27.4523ZM15.1455 21.3273C15.5349 21.3273 15.9155 21.4428 16.2393 21.6591C16.563 21.8755 16.8154 22.1829 16.9644 22.5427C17.1134 22.9024 17.1524 23.2983 17.0764 23.6802C17.0005 24.0621 16.813 24.4129 16.5376 24.6882C16.2623 24.9635 15.9115 25.151 15.5296 25.227C15.1477 25.303 14.7518 25.264 14.3921 25.115C14.0324 24.966 13.7249 24.7136 13.5086 24.3899C13.2922 24.0661 13.1768 23.6855 13.1768 23.2961C13.1768 22.7739 13.3842 22.2732 13.7534 21.904C14.1226 21.5348 14.6234 21.3273 15.1455 21.3273Z\" fill=\"#0BAE79\"><\/path><path d=\"M35.5625 27.4523C36.3845 27.4523 37.1881 27.2086 37.8716 26.7519C38.5551 26.2952 39.0878 25.6461 39.4024 24.8866C39.717 24.1272 39.7993 23.2915 39.6389 22.4852C39.4785 21.679 39.0827 20.9384 38.5014 20.3572C37.9201 19.7759 37.1796 19.3801 36.3733 19.2197C35.5671 19.0593 34.7314 19.1416 33.972 19.4562C33.2125 19.7708 32.5634 20.3035 32.1067 20.987C31.65 21.6705 31.4062 22.4741 31.4062 23.2961C31.4062 24.3984 31.8441 25.4555 32.6236 26.235C33.403 27.0144 34.4602 27.4523 35.5625 27.4523ZM35.5625 21.3273C35.9519 21.3273 36.3325 21.4428 36.6563 21.6591C36.98 21.8755 37.2324 22.1829 37.3814 22.5427C37.5304 22.9024 37.5694 23.2983 37.4934 23.6802C37.4175 24.0621 37.23 24.4129 36.9546 24.6882C36.6793 24.9635 36.3285 25.151 35.9466 25.227C35.5647 25.303 35.1688 25.264 34.8091 25.115C34.4493 24.966 34.1419 24.7136 33.9255 24.3899C33.7092 24.0661 33.5938 23.6855 33.5938 23.2961C33.5938 22.7739 33.8012 22.2732 34.1704 21.904C34.5396 21.5348 35.0404 21.3273 35.5625 21.3273Z\" fill=\"#0BAE79\"><\/path><path d=\"M35.708 29.6464C34.7492 29.6527 33.8071 29.8982 32.9671 30.3606C32.1685 29.0963 31.0678 28.0507 29.7642 27.3181C28.4606 26.5854 26.9952 26.1888 25.5 26.1639C24.0049 26.1888 22.5394 26.5854 21.2359 27.3181C19.9323 28.0507 18.8316 29.0963 18.033 30.3606C17.193 29.8982 16.2509 29.6527 15.2921 29.6464C13.5715 29.7303 11.954 30.4916 10.7927 31.7639C9.63141 33.0363 9.02066 34.7164 9.09377 36.4375C9.09377 36.7276 9.20901 37.0058 9.41413 37.2109C9.61924 37.416 9.89744 37.5312 10.1875 37.5312C10.4776 37.5312 10.7558 37.416 10.9609 37.2109C11.166 37.0058 11.2813 36.7276 11.2813 36.4375C11.2096 35.2968 11.5904 34.1738 12.3412 33.312C13.092 32.4502 14.1523 31.9191 15.2921 31.8339C15.8965 31.8385 16.4899 31.9962 17.0169 32.2922C16.5014 33.5912 16.2375 34.9764 16.2392 36.374C16.2392 36.6641 16.3545 36.9423 16.5596 37.1474C16.7647 37.3526 17.0429 37.4678 17.333 37.4678C17.6231 37.4678 17.9013 37.3526 18.1064 37.1474C18.3115 36.9423 18.4267 36.6641 18.4267 36.374C18.4267 31.9498 21.5986 28.3514 25.5 28.3514C29.4014 28.3514 32.5733 31.9498 32.5733 36.374C32.5733 36.6641 32.6885 36.9423 32.8937 37.1474C33.0988 37.3526 33.377 37.4678 33.6671 37.4678C33.9571 37.4678 34.2353 37.3526 34.4405 37.1474C34.6456 36.9423 34.7608 36.6641 34.7608 36.374C34.7625 34.9764 34.4986 33.5912 33.9831 32.2922C34.5102 31.9962 35.1036 31.8385 35.708 31.8339C36.8478 31.9191 37.908 32.4502 38.6588 33.312C39.4096 34.1738 39.7905 35.2968 39.7188 36.4375C39.7188 36.7276 39.834 37.0058 40.0391 37.2109C40.2442 37.416 40.5224 37.5312 40.8125 37.5312C41.1026 37.5312 41.3808 37.416 41.5859 37.2109C41.791 37.0058 41.9063 36.7276 41.9063 36.4375C41.9794 34.7164 41.3686 33.0363 40.2074 31.7639C39.0461 30.4916 37.4286 29.7303 35.708 29.6464Z\" fill=\"#0BAE79\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tR\u00e9seau de voisinage\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVos contacts durgence seront souvent vos proches, votre famille ou des amis proches. \n\nVotre r\u00e9seau peut aussi \u00eatre compos\u00e9 de voisins que vous avez s\u00e9lectionn\u00e9s. Connectez-vous avec des personnes de votre quartier. \n\nPartagez de laide, recevez des messages et faites partie dune communaut\u00e9 num\u00e9rique de s\u00e9curit\u00e9.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-529a776 e-con-full e-flex e-con e-child\" data-id=\"529a776\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-218423c elementor-widget elementor-widget-image\" data-id=\"218423c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"624\" height=\"395\" src=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Nabonetvaerk.png\" class=\"attachment-full size-full wp-image-2204\" alt=\"\" srcset=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Nabonetvaerk.png 624w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Nabonetvaerk-300x190.png 300w\" sizes=\"(max-width: 624px) 100vw, 624px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e371a07 e-con-full e-flex e-con e-child\" data-id=\"e371a07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5c888e6 e-con-full e-flex e-con e-child\" data-id=\"5c888e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9248a9c elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9248a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"52\" viewBox=\"0 0 52 52\" fill=\"none\"><circle cx=\"26\" cy=\"26\" r=\"26\" fill=\"#F0F0F0\"><\/circle><path d=\"M36.293 26.4557V23.2773C36.293 18.6407 33.2111 14.7109 28.9884 13.4273V11.9883C28.9884 10.3405 27.6478 9 26.0001 9C24.3523 9 23.0118 10.3405 23.0118 11.9883V13.4273C18.789 14.7109 15.7071 18.6407 15.7071 23.2773V26.4557C15.7071 30.5285 14.1547 34.3904 11.3358 37.3301C11.0595 37.6182 10.9819 38.0432 11.1385 38.4103C11.2951 38.7774 11.6557 39.0156 12.0548 39.0156H21.1198C21.5825 41.2862 23.5949 43 26.0001 43C28.4053 43 30.4176 41.2862 30.8803 39.0156H39.9454C40.3445 39.0156 40.705 38.7774 40.8616 38.4103C41.0182 38.0432 40.9406 37.6182 40.6644 37.3301C37.8455 34.3904 36.293 30.5284 36.293 26.4557ZM25.004 11.9883C25.004 11.439 25.4508 10.9922 26.0001 10.9922C26.5493 10.9922 26.9962 11.439 26.9962 11.9883V13.0327C26.6683 13.0011 26.3361 12.9844 26.0001 12.9844C25.6641 12.9844 25.3318 13.0011 25.004 13.0327V11.9883ZM26.0001 41.0078C24.7015 41.0078 23.5943 40.175 23.1831 39.0156H28.817C28.4058 40.175 27.2987 41.0078 26.0001 41.0078ZM14.2017 37.0234C16.4702 33.9826 17.6993 30.3026 17.6993 26.4557V23.2773C17.6993 18.7003 21.423 14.9766 26.0001 14.9766C30.5771 14.9766 34.3009 18.7003 34.3009 23.2773V26.4557C34.3009 30.3026 35.53 33.9826 37.7985 37.0234H14.2017Z\" fill=\"#FCA401\"><\/path><path d=\"M38.9492 23.2773C38.9492 23.8274 39.3952 24.2734 39.9453 24.2734C40.4954 24.2734 40.9414 23.8274 40.9414 23.2773C40.9414 19.2863 39.3872 15.5341 36.5652 12.7121C36.1762 12.3231 35.5455 12.3231 35.1565 12.7121C34.7675 13.1011 34.7675 13.7317 35.1565 14.1208C37.6023 16.5666 38.9492 19.8184 38.9492 23.2773Z\" fill=\"#FCA401\"><\/path><path d=\"M12.0547 24.2734C12.6048 24.2734 13.0508 23.8274 13.0508 23.2773C13.0508 19.8185 14.3978 16.5667 16.8435 14.1208C17.2325 13.7318 17.2325 13.1012 16.8435 12.7122C16.4546 12.3232 15.8238 12.3232 15.4348 12.7122C12.6128 15.5342 11.0586 19.2863 11.0586 23.2773C11.0586 23.8274 11.5046 24.2734 12.0547 24.2734Z\" fill=\"#FCA401\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNotifications  alarme personnelle\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRecevez une notification lorsque quelquun, dont vous \u00eates le contact durgence, appuie sur le bouton. Contactez directement par appel depuis lapplication et b\u00e9n\u00e9ficiez dune pr\u00e9sence plus proche et plus rassurante.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc0ce0d e-con-full e-flex e-con e-child\" data-id=\"bc0ce0d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-684929f elementor-widget elementor-widget-image\" data-id=\"684929f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"619\" height=\"379\" src=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Notifikationer-Personlig-alarm.png\" class=\"attachment-full size-full wp-image-2205\" alt=\"\" srcset=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Notifikationer-Personlig-alarm.png 619w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Notifikationer-Personlig-alarm-300x184.png 300w\" sizes=\"(max-width: 619px) 100vw, 619px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e2c9bc e-con-full e-flex e-con e-child\" data-id=\"4e2c9bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5d849c0 e-con-full e-flex e-con e-child\" data-id=\"5d849c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-557ede9 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"557ede9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"52\" height=\"52\" viewBox=\"0 0 52 52\" fill=\"none\"><circle cx=\"26\" cy=\"26\" r=\"26\" fill=\"#F0F0F0\"><\/circle><path d=\"M11.6865 18.0908C14.4641 14.3721 21.9256 14.0234 25.126 21.3389L26.5 24.4795L27.874 21.3389C31.0742 14.0275 38.5357 14.3756 41.3135 18.0938C42.6631 19.9003 43.1726 22.8062 41.1514 26.6904C39.164 30.5093 34.7513 35.1807 26.5 40.2451C18.2487 35.1807 13.836 30.5088 11.8486 26.6895C9.82737 22.8047 10.3368 19.8979 11.6865 18.0908Z\" stroke=\"#C1353D\" stroke-width=\"3\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNotifications  statut\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tQue vous soyez utilisateur de Tryghedsappen ou que vous souhaitiez simplement \u00eatre le contact durgence dune personne qui vous est ch\u00e8re, vous recevrez une invitation \u00e0 devenir contact durgence. \n\nCest \u00e0 vous de d\u00e9cider si vous souhaitez accepter et contribuer \u00e0 un quotidien plus s\u00fbr pour une ou plusieurs personnes qui vous sont ch\u00e8res.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eacd4d0 e-con-full e-flex e-con e-child\" data-id=\"eacd4d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e19d6d4 elementor-widget elementor-widget-image\" data-id=\"e19d6d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1740228099-scaled.jpg\" class=\"attachment-full size-full wp-image-2216\" alt=\"\" srcset=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1740228099-scaled.jpg 2560w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1740228099-300x200.jpg 300w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1740228099-1024x683.jpg 1024w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1740228099-768x512.jpg 768w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1740228099-1536x1024.jpg 1536w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2026\/02\/iStock-1740228099-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-342b153 e-flex e-con-boxed e-con e-parent\" data-id=\"342b153\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5585e0f elementor-widget elementor-widget-heading\" data-id=\"5585e0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00eat(e) \u00e0<\/br>\n commencer ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ba9ce5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4ba9ce5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>T\u00e9l\u00e9chargez lapplication gratuitement et d\u00e9couvrez comment une simple pression peut apporter plus de s\u00e9curit\u00e9 \u2014 pour vous et votre entourage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d6ec81 e-con-full e-flex e-con e-child\" data-id=\"1d6ec81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ee3f4a8 e-con-full e-flex e-con e-child\" data-id=\"ee3f4a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93a406c elementor-widget elementor-widget-image\" data-id=\"93a406c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"467\" height=\"156\" src=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Black-BG.png\" class=\"attachment-full size-full wp-image-2081\" alt=\"\" srcset=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Black-BG.png 467w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Black-BG-300x100.png 300w\" sizes=\"(max-width: 467px) 100vw, 467px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18e122c e-con-full e-flex e-con e-child\" data-id=\"18e122c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57fa03b elementor-widget elementor-widget-image\" data-id=\"57fa03b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"156\" src=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Google-Play2.png\" class=\"attachment-full size-full wp-image-2082\" alt=\"\" srcset=\"https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Google-Play2.png 540w, https:\/\/tryghedsappen.dk\/wp-content\/uploads\/2025\/10\/Google-Play2-300x87.png 300w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-666452e e-flex e-con-boxed e-con e-parent\" data-id=\"666452e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-83c9314 e-con-full e-flex e-con e-child\" data-id=\"83c9314\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-85254ac e-con-full e-flex e-con e-child\" data-id=\"85254ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2fd03c elementor-widget elementor-widget-heading\" data-id=\"e2fd03c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9 et RGPD<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c46ecd4 elementor-widget elementor-widget-text-editor\" data-id=\"c46ecd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez comment nous collectons, stockons et prot\u00e9geons vos informations. Notre principe est que vos donn\u00e9es vous appartiennent \u2014 nous ne collectons donc que le strict n\u00e9cessaire pour que lapplication vous apporte la s\u00e9curit\u00e9 que vous souhaitez. Vous pouvez en savoir plus via ce lien :  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb6bb53 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bb6bb53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lire lint\u00e9gralit\u00e9 de notre politique de confidentialit\u00e9 \u2192<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7314da1 e-con-full e-flex e-con e-child\" data-id=\"7314da1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7999e56 elementor-widget elementor-widget-heading\" data-id=\"7999e56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9l\u00e9charger vos donn\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa467de elementor-widget elementor-widget-text-editor\" data-id=\"fa467de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tSouhaitez-vous une copie de vos informations ? Vous pouvez demander \u00e0 t\u00e9l\u00e9charger vos donn\u00e9es enregistr\u00e9es \u00e0 tout moment.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4077eb8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4077eb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Demander un export de donn\u00e9es \u2192<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9f5d88 e-con-full e-flex e-con e-child\" data-id=\"f9f5d88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a28a8a3 e-con-full e-flex e-con e-child\" data-id=\"a28a8a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abdd51e elementor-widget elementor-widget-heading\" data-id=\"abdd51e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conditions g\u00e9n\u00e9rales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2e9ebf elementor-widget elementor-widget-text-editor\" data-id=\"f2e9ebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Il est important que vous preniez connaissance des conditions g\u00e9n\u00e9rales dutilisation de lapplication. Elles sont d\u00e9crites dans un document que vous pouvez t\u00e9l\u00e9charger ici : <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-947ddd9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"947ddd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lire les conditions g\u00e9n\u00e9rales dutilisation de lapplication \u2192<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a590c18 e-con-full e-flex e-con e-child\" data-id=\"a590c18\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0ca638 elementor-widget elementor-widget-heading\" data-id=\"f0ca638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Suppression du compte et des donn\u00e9es<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6330826 elementor-widget elementor-widget-text-editor\" data-id=\"6330826\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tVous avez toujours le droit de faire supprimer votre compte et toutes les donn\u00e9es associ\u00e9es. Cela prend g\u00e9n\u00e9ralement jusqu\u00e0 24 heures. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c82573 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0c82573\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Supprimer mon compte et mes donn\u00e9es \u2192<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fonctionnalit\u00e9s \u2013 S\u00e9curit\u00e9 au quotidien Tryghedsappen est une application mobile d\u00e9velopp\u00e9e au Danemark, con\u00e7ue pour apporter de la s\u00e9curit\u00e9 au quotidien \u2014 pour vous, vos proches et votre r\u00e9seau. Dune simple pression, vous pouvez alerter vos contacts durgence, partager votre position et obtenir un contact ou de laide le plus rapidement possible, lorsque vous en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-2201","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/tryghedsappen.dk\/fr\/wp-json\/wp\/v2\/pages\/2201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tryghedsappen.dk\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tryghedsappen.dk\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tryghedsappen.dk\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tryghedsappen.dk\/fr\/wp-json\/wp\/v2\/comments?post=2201"}],"version-history":[{"count":1,"href":"https:\/\/tryghedsappen.dk\/fr\/wp-json\/wp\/v2\/pages\/2201\/revisions"}],"predecessor-version":[{"id":2219,"href":"https:\/\/tryghedsappen.dk\/fr\/wp-json\/wp\/v2\/pages\/2201\/revisions\/2219"}],"wp:attachment":[{"href":"https:\/\/tryghedsappen.dk\/fr\/wp-json\/wp\/v2\/media?parent=2201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}